{"id":263,"date":"2016-05-04T10:06:05","date_gmt":"2016-05-04T08:06:05","guid":{"rendered":"http:\/\/sites.unica.it\/prion\/?page_id=263"},"modified":"2016-05-04T10:06:05","modified_gmt":"2016-05-04T08:06:05","slug":"lecturers-2015","status":"publish","type":"page","link":"https:\/\/sites.unica.it\/prion\/edition-2015\/lecturers-2015\/","title":{"rendered":"Lecturers 2015"},"content":{"rendered":"<h4>en<\/h4><p><\/p>\n<p style=\"text-align: justify\"><em><strong><br \/>\n<a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-75\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-214x300.png\" alt=\"CapucciL\" width=\"164\" height=\"230\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-214x300.png 214w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-732x1024.png 732w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL.png 849w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>L<\/strong><strong>orenzo Capucci.<\/strong><\/em>\u00a0graduated in Biological Science at the State University of Milano in 1981. He works at the Istituto Zooprofilattico Sperimentale della Lombardia e dell\u2019 Emilia Romagna (IZSLER) since 1983. At present he is responsible of the Proteomic Structures\/Genomics-Department at IZSLER. He is working on the diagnosis and study of the main viral diseases of lagomorphs (RHDV, European brown hare syndrome and myxomatosis), and developing specific immunological diagnostic techniques for these viruses since 1990. He is the expert for Rabbit Haemorrhagic Disease (RHD) Reference Laboratory of the World Organization for animal Health (OIE). Lorenzo Capucci has been collaborating with Australian Scientists from CSIRO and State Departments for over 20 years as senior advisor on RHDV epidemiology and antigenic characterization. He is a responsible for one of the main Italian laboratory for rapid diagnosis of Bovine Spongiform Encephalopathy (BSE) since 2000.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CardoneF.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-76\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CardoneF.jpg\" alt=\"CardoneF\" width=\"164\" height=\"229\" \/><\/a>Franco Cardone.<\/strong><\/em>\u00a0Born in 1969, formally a biologist (MSc) and a biochemist (PhD) graciously awarded by the Universities of Lecce and Rome &#8220;La Sapienza&#8221;. Actually intrigued by everything that moves and active supporter of the scientific method even at the supermarket, I started working on prions thanks to the sympathy for my microbiology professor at the university (my current beloved boss!); I still stay on the move because I have talented colleagues, a sparkling family and a great passion for a topic that challenges logical reasoning and established scientific beliefs. During these years I had the chance to join dozens of projects and co-author many publications, and I feel privileged because I can go on with this work in spite of the many daily problems. During my adulthood I would like to study neuronal regeneration, but likely I will quit before that&#8230;. Researcher at the Istituto Superiore di Sanit\u00e0 in the laboratory of Virology since 1993, I am first researcher in the forthcoming Department of Neurosciences of the Istituto Superiore di Sanit\u00e0. Involved in more than 70 scientific papers (articles, reviews, chapters) on the pathogenesis, biochemistry, diagnosis, decontamination and other branches of prion diseases, I also worked as scientific and unit leader in several research projects. I had the pleasure to be invited as a speaker in scientific meetings, conferences, and seminars.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CossuG.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-77\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CossuG.jpg\" alt=\"CossuG\" width=\"164\" height=\"192\" \/><\/a>Giovanni Cossu.<\/strong><\/em>\u00a01993, Doctoral degree in medicine and surgery (MD equivalent); 1998, Neurology Residency, University of Cagliari. Since 1999, Medical Doctor Neurology Unit A.O. Brotzu Cagliari, and Collaborator of the Stroke Unit team. 2009 to present: Director of Parkinson\u2019s disease and Movement Disorders Section A.O. Brotzu Cagliari. Clinical and research activity in Clinical Neurophysiology, functional neurosurgery (DBS) and botulinum toxin treatment in Parkinson Disease and Movement Disorders at the Movement Disorders Unit, Hospital Clinic in Barcelona. Clinical activity in functional neurosurgery (DBS) in movement disorders at the Neurological Institute Besta, Milan. Research visitor at the Institute of Neurology, Movement Disorders and DBS Unit Queen Square, London, UK. Author or coauthor of abot 50 articles in peer-reviewed journals; serves as referee for the journals Movement Disorders, Parkinsonism Related Disorders, Parkinson Disease, Neurologucal Sciences, Clinical Neurophysiology.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-78\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS-242x300.jpg\" alt=\"FerrariS\" width=\"164\" height=\"203\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS-242x300.jpg 242w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS.jpg 276w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Sergio Ferrari.<\/strong><\/em><\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FioriniM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-79\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FioriniM.jpg\" alt=\"FioriniM\" width=\"164\" height=\"125\" \/><\/a>Michele Fiorini.\u00a0<\/strong><\/em>After graduating in Agro-industrial Biotechnology (October 2000), I started attending the Laboratory of Neuropathology of the Department of Neurological and Movement Sciences and in May 2005 I obtained my PhD in Industrial and Environmental biotechnology with a thesis entitled &#8220;Diagnostic role of 14-3-3 proteins typing in the CSF of Creutzfeldt-Jakob disease &#8220;. Since July 2001 I\u2019ve been holder of research grants always at the Neuropathology Laboratory of the Department of Neurological and Movement Sciences of the University of Verona. I have always been involved in prion diseases (human and animal) Proteomics, in particular in terms of biochemical characterization of prions and associated molecular markers; I\u2019ve been also interested in CSF and tissue proteomics in other neurodegenerative diseases, and in searching for and characterizing of new molecular markers of disease. In the Neuropathology Laboratory I also deal with in molecular diagnosis of neurodegenerative diseases.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-80\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG-291x300.png\" alt=\"LegnameG\" width=\"164\" height=\"169\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG-291x300.png 291w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG.png 297w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Giuseppe Legname.\u00a0<\/strong><\/em>Earned his Doctor of Philosophy at the University of Warwick, UK. After a long spell in industry in the field of immunotherapy, he moved to the National Institute for Medical Research, Medical Research Council in London, UK as a Research Associate. In 1999 he became Assistant Adjunct Professor, and later Associate Adjunct Professor, at the Institute for Neurodegenerative Diseases, University of California at San Francisco, USA, under the direction of 1997 Nobel Laureate Professor Stanley B. Prusiner. Since then he has been involved in basic research projects in the field of Prion Biology and Disease. In 2006, he joined the faculty of SISSA in Trieste as Associate Professor at the Department of Neuroscience.<br \/>\nCurrently, he is the Coordinator of the PhD Program in Functional and Structural Genomics and faculty of the PhD Program in Molecular Biology at SISSA and member-elect of the Academic Senate. He has authored over 150 peer-reviewed papers, books and book chapters. He is currently serving as reviewer and academic editor for several International Journals and he is co-author of various patents. The main focus of his research program is the physiological function of the prion protein in mammals and the mechanisms of prion replication as well as the structural characterization of molecular determinants for prion infectivity in Prion Diseases. More recently, he has started new lines of research in prion-like disorders.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-81\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC-240x300.png\" alt=\"LigiosC\" width=\"164\" height=\"205\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC-240x300.png 240w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC.png 272w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Ciriaco Ligios.<\/strong><\/em><\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/Mandas-e1434957377419.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-96\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/Mandas-e1434957377419.jpg\" alt=\"Mandas\" width=\"164\" height=\"215\" \/><\/a>Antonella Mandas.\u00a0<\/strong><\/em>Degree in Medicine, since 2006 is associate professor of internal medicine at the Department of Medical Sciences, University of Cagliari. She has taken part in clinical and epidemiological studies on the hepatic virus and HIV infections. In particular, she has taken part in major clinical trials on interferon used in patients with chronic viral hepatitis. She has conducted studies on oxidative stress in geriatric and in HIV-infected subjects. In the elderly, it was highlighted the connection between oxidative stress, comorbidities, and nutritional status. In HIV-infected it was highlighted that antiretroviral therapy may increase the oxidative stress. In peripheral blood mononuclear cells from patients with Alzheimer&#8217;s disease she studied the role of cholesterol alterations. These studies made possible to propose the determination of cholesterol esters in lymphomonocytes peripheral as early biomarkers of Alzheimer&#8217;s disease. In addition, she conducts studies on the correlation between the intake of lipid-lowering drugs (statins) and cognitive impairment in the elderly. Since 2007 she is the Director of the Geriatric Postgraduate School and she conducts studies on comprehensive geriatric assessment, as early indicator of the condition of frailty in elderly.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/MeloniD.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-170\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/MeloniD-285x300.jpg\" alt=\"MeloniD\" width=\"164\" height=\"173\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/MeloniD-285x300.jpg 285w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/MeloniD.jpg 590w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Daniela Meloni.\u00a0<\/strong><\/em>Senior Veterinarian, Head of Laboratory of TSE rapid tests of the National Reference Centre for the le Animal Encephalopathies set in the Istituto Zooprofilattico Sperimentale of Piemonte, Liguria and Valle d\u2019Aosta. Responsible for management and coordination of rapid diagnostic activities. Experience in setting up and coordinating surveillance statutory planes in collaboration with National authorities. Delves into all aspects of TSE rapid diagnostic methods. Wide activities in training people and conference talk in TSE matters. Auditor to verify conformity to UNI EN ISO 17025 of Italian Rapid Test Laboratories. Author and co-author in research projects published in national and international papers national and international meetings on TSE surveillance and diagnostics.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PaniA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-82\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PaniA.jpg\" alt=\"PaniA\" width=\"164\" height=\"156\" \/><\/a>Alessandra Pani.\u00a0<\/strong><\/em>Virologist, is associate professor of microbiology and virology at the Department of Biomedical Sciences, University of Cagliari, since 2005. Main interests are the drug discovery of antivirals, in particular identification and preclinical characterization of novel classes of HIV inhibitors, and of anticancer agents, especially drug combinations with synergistic activity, in vitro and in vivo. As CNR-fellow at the Department of Virology of the London Hospital Medical College, London, she investigated the mechanisms of the natural resistance to herpes virus infection in inbred mice, and during her post-doc in the Department of Cellular and Molecular Biology of the University of Connecticut, USA, she studied the mechanisms of the shut-off of protein synthesis in cells infected with picornaviruses. In more recent years, after a short visit at the TSE Biochemistry Section of the Department of Persistent Viral Diseases, RML, NIAID \/ NIH, USA, with some post-docs and graduated students of her group she has begun to investigate some aspects of prion and prion-like diseases; in particular the role cholesterol and lipids in the generation of amyloid, and prions detection in in vitro amplification assays. Presently, s he is the Coordinator of the PhD Program in R&amp;D of Antinfettive Drugs and Vicecoordinator of the PhD Program in Molecular and Translational Medicine.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PocchiariM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-83\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PocchiariM.jpg\" alt=\"PocchiariM\" width=\"164\" height=\"203\" \/><\/a>Maurizio Pocchiari.<\/strong><\/em>\u00a0Neurologist and director of the Department of Cellular Biology and Neurosciences of the Istituto Superiore di Sanit\u00e0, Roma. Since 1993, Pocchiari is responsible for the Italian national surveillance of Creutzfeldt-Jakob disease. Pocchiari is member of the \u201cEUROCJD (Public Health Surveillance) Steering Group\u201d, European Centre for Disease Prevention and Control (ECDC). Since 1978, Pocchiari research interest is in the field of prion diseases..<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/07\/MariaPuopolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-208\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/07\/MariaPuopolo-150x150.jpg\" alt=\"MariaPuopolo\" width=\"164\" height=\"164\" \/><\/a>Maria Puopolo.\u00a0<\/strong><\/em>Statistician, researcher at the Department of Cell Biology and Neuroscience of the Istituto Superiore di Sanit\u00e0, Roma. Since 2001 Puopolo works in the field of prion diseases being involved in analysis of data from Italian national and European (EUROCJD) surveillance of Creutzfeldt-Jakob disease. In 2014 she is consultant for European Centre for Disease Prevention and Control (ECDC) for analysis of TESSy vCJD database. She has a long term experience in statistical methodologies for analysis of: i) determinants of progression\/severity of disease; ii) risk and protective factors; iii) development and validation of biomarkers; iv) assessment of efficacy of experimental treatments.<em><strong><br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-84\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV-248x300.jpg\" alt=\"VetrugnoV\" width=\"164\" height=\"198\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV-248x300.jpg 248w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV.jpg 308w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Vito Vetrugno.\u00a0<\/strong><\/em>Degree in Biological Sciences (summa cum laude) at the University of Lecce (1992). Specialty school in \u201cMicrobiology and Medical Virology\u201d (70\/70 cum laude) at the University of Rome \u201cLa Sapienza\u201d (1998). Since 1992 to date, researcher at \u201cIstituto Superiore di Sanit\u00e0\u201d, in Rome. Since 2009, Contract Professor for the learning of \u201cMethodology of Research\u201d in the First Level Universitary Master \u201cManagement della Professione Sanitaria\u201d, Universit\u00e0 Cattolica del Sacro Cuore, Rome. Since 2010, Chair of the Transmissible Spongiform Encephalopathies Group (GESTISS), at Istituto Superiore di Sanit\u00e0. His main area of interest is the impact of Transmissible Spongiform Encephalopathies (TSE or prion diseases) on public health. On that account he is involved in an extensive activity concerning pre-normative research, regulatory issues and consultancy, drawing up more than 400 scientific advices and TSE risk assessments. As scientist, he is involved in the study of the cellular biology of the prion protein, its conversion into the pathological isoform, and in the developing of potential therapeutic approaches against TSE in preclinical models.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/ZanussoG.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-85\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/ZanussoG.jpg\" alt=\"ZanussoG\" width=\"164\" height=\"212\" \/><\/a>Gianluigi Zanusso.\u00a0<\/strong><\/em>Associate professor in neurology at the Department of Neurological Movement, University of Verona since 2014. He started to work on prion diseases in 1995, firstly studying the molecular mechanisms of prion aggregation in cellular models of genetic forms, then he devoted his studies to clinical aspects of human disease with particular interest to the involvement of the olfactory system and in vitam diagnostics of the Creutzfeldt-Jakob disease (CJD). From 2001 to 2007 he was member of the Ministerial Commission Task Force of the National Transmissible Spongiform Encephalopathies. Recently, in collaboration with the group of Dr. Caughey of NIAID in Montana, he has developed a test in vitam (CJD) through nasal brushing.<\/p>\n<p style=\"text-align: justify\"><\/p><h4>it<\/h4><p><\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-75\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-214x300.png\" alt=\"CapucciL\" width=\"164\" height=\"230\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-214x300.png 214w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL-732x1024.png 732w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/CapucciL.png 849w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>L<\/strong><strong>orenzo Capucci.<\/strong><\/em>\u00a0Nato a Cremona il 23.12.1954, dopo 3 settimane seguo mia madre, che torna da mio padre, che \u00e8 geometra minerario in quel di Gennamari (porta sul mare), comune di Arbus, Continente Sardegna. Vivo 18 anni in Sardegna, poi mio padre ci lascia per andare a caccia di pernici nelle celesti praterie. La famiglia torna al nord, citta di Brescia. Mi laureo in Biologia all\u2019Universit\u00e0 Statale di Milano nel febbraio del 1981, giusto fra il CAR e CAR avanzato (servizio Militare) svolto rinchiuso nella caserma Monfenera &#8211; Cagliari. Sopravvivo grazie ai generosi e sfiziosi panini di via Mannu. Seguiranno 9 mesi a Perdasdefogu \u2013 Salto di Quirra, come assistente medico, con qualche scappata alle spiagge fra Tortol\u00ec ed Arbatax. Tornato a Brescia, approdo all\u2019Istituto Zooprofilattico come borsista, ove tutt\u2019ora lavoro. In realt\u00e0 il mio bagaglio professionale lo devo a Paolo Plevani, mio relatore di tesi appena rientrato dagli USA: \u00e8 lui che mi insegna il lavoro. In quegli anni \u00e8 in pieno avvio la \u201crivoluzione del DNA\u201d, ma a me attrare di pi\u00f9 la fantasia ed il balletto dei 20 amino acidi. Ho poi la fortuna di lavorare con colleghi che, letto nel 1975 l\u2019articolo di K\u00f6hler e Milstein sugli anticorpi monoclonali, dal 1982 cominciano a produrne di stupendi. Agli inizi lavoro sul virus dell\u2019Afta Epizootica, ma la svolta \u00e8 del 1989: mi chiedono di lavorare su un nuovo virus che causa un epatite acuta nei conigli, facendone stragi. Da li ad oggi molto \u00e8 stato il lavoro sui virus dei lagomorfi (conigli e lepri), con un interruzione all\u2019incirca fra il 2000 ed il 2005, per una nuova emergenza: la BSE. Quale amante della fantasie delle proteine, di cui i prioni sono notevole esempio, e visto che gli esperti di acidi nucleici una volta tanto poco possono, nel 1999 mi dicono che devo interessarmi di diagnosi di TSE. Agli inizi sembra una normale storia sul viale del tramonto. In realt\u00e0 a breve scoppier\u00e0 il finimondo, che cercher\u00f2 di raccontare come laboratorista e sui cui cercheremo di riflettere con chi avr\u00e0 la voglia e pazienza di ascoltami.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CardoneF.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-76\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CardoneF.jpg\" alt=\"CardoneF\" width=\"164\" height=\"229\" \/><\/a>Franco Cardone.<\/strong><\/em>\u00a0\u00a0Nato nel 1969, sulla carta biologo (Universit\u00e0 di Lecce) e biochimico (Universit\u00e0\u00a0\u00a0La Sapienza), in realt\u00e0 curioso di tutto ci\u00f2 che si muove e profondo sostenitore del metodo scientifico anche al supermercato, ho cominciato a lavorare sui prioni perch\u00e9 il mio professore dell\u2019epoca mi stava (e mi sta!) molto simpatico; ho continuato a farlo perch\u00e9 ho dei colleghi in gamba, una famiglia che mi da entusiasmo e perch\u00e9 \u00e8 un argomento che ancora oggi sfida la logica e ci\u00f2 che sta scritto nei libri. Ho avuto la buona sorte di partecipare ad alcune decine di progetti e lavori scientifici e pur facendo una grande fatica, sono molto fortunato perch\u00e9 posso continuare a farlo. Da grande vorrei occuparmi di rigenerazione neuronale, ma forse smetter\u00f2 prima\u2026\u2026<br \/>\nRicercatore dell\u2019Istituto Superiore di Sanit\u00e0 dal 1993 nel laboratorio di Virologia, attualmente primo ricercatore del costituendo Dipartimento di Neuroscienze. Coautore di oltre 70 pubblicazioni scientifiche (articoli, review, capitoli di libri) su patogenesi, biochimica, diagnosi, decontaminazione e altri aspetti della biologia delle malattie da prioni. Responsabile scientifico e di unit\u00e0 operative in vari progetti di ricerca. Relatore in convegni, corsi, lezioni universitarie e per la preparazione di tesi di laurea magistrale e di dottorato.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CossuG.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-77\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/CossuG.jpg\" alt=\"CossuG\" width=\"164\" height=\"192\" \/><\/a>Giovanni Cossu.<\/strong><\/em>\u00a0Nato a Cagliari nel 1967. Laurea in Medicina e Chirurgia e Specializzazione in Neurologia conseguita presso Universit\u00e0 degli Studi di Cagliari. Riveste il ruolo di Dirigente Medico di I\u00b0 livello, Divisione Neurologia dell\u2019A.O. Brotzu Cagliari. Ha svolto attivit\u00e0 clinica e di ricerca in neurofisiologia clinica, tossina botulinica, neurostimolazione cerebrale profonda (DBS) in Parkinson e disturbi del movimento presso Movement Disorders Unit, Hospital Clinic Barcelon e presso Neurologia e Neurochirurgia, e Istituto Besta di Milano. Dal 2012 \u00e8 Honorary contractor DBS Unit -UCL Institute of Neurology National Hospital for Neurology and Neurosurgery Queen Square, London. E\u2019 Responsabile del Centro Parkinson AO Brotzu. E\u2019 autore e coautore di circa 50 articoli pubblicati su riviste indicizzate; collabora come referee con diverse riviste di neurologia come Movement Disorders, Parkinsonism Related Disorders, Parkinson Disease, Neurologucal Sciences, Clinical Neurophysiology.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-78\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS-242x300.jpg\" alt=\"FerrariS\" width=\"164\" height=\"203\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS-242x300.jpg 242w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/FerrariS.jpg 276w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Sergio Ferrari.<\/strong> <\/em>Nato a Verona il 29 Agosto 1955. Ha conseguito il Diploma di Maturita&#8217; Scientifica nel luglio 1974. E\u2019 laureato in Medicina e Chirurgia (1981), specializzato in Neurologia (1985) e in Neuropatologia (1989).Dal 22\/5\/89 \u00e8 Dirigente medico di I livello a tempo pieno presso la Clinica Neurologica dell\u2019Universit\u00e0 di Verona dell\u2019Azienda Ospedaliera di Verona. Consulente Neurologo presso l\u2019Istituto di Malattie Infettive dell&#8217;Universit\u00e0 degli Studi di Verona. E\u2019 membro del direttivo della\u2019Associazione Italiana di Neuropatologia e del Gruppo di Studio di Neuroinfettivologia. Dal 1 agosto 1997 al 30 ottobre 1997 e nel settembre 2009 ha svolto soggiorni di studio presso la Division of Neuropathology, Institute of Pathology, Case Western Reserve University, Cleveland, OH, USA, diretta dal prof. Pierluigi Gambetti. E\u2019 autore o coautore di circa 80 pubblicazioni scientifiche in extenso. Principali interessi di studio e di ricerca clinica: Neuropatologia, Malattie da Prioni, Neuroimmunologia, Malattie Infettive del Sistema Nervoso, NeuroAIDS, Neuropatie Periferiche, Malattie degenerative del Sistema Nervoso.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FioriniM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-79\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/FioriniM.jpg\" alt=\"FioriniM\" width=\"164\" height=\"125\" \/><\/a>Michele Fiorini.<\/strong><\/em>\u00a0Dopo la laurea in Biotecnologie agro-industriali (ottobre 2000) ho iniziato a frequentare il Laboratorio di Neuropatologia del Dipartimento di Scienze Neurologiche e del Movimento e nel maggio 2005 ho conseguito il dottorato di ricerca in Biotecnologie industriali ed ambientali discutendo la tesi dal titolo: &#8220;Ruolo diagnostico della tipizzazione delle proteine 14-3-3 liquorali nella Malattia di Creutzfeldt-Jakob&#8221;. Da luglio 2001 ad oggi sono titolare di borse di studio e assegni di ricerca sempre presso il Laboratorio di Neuropatologia del Dipartimento di Scienze Neurologiche e del Movimento dell\u2019Universit\u00e0 degli Studi di Verona. Mi sono sempre occupato di malattie da prioni (umane e animali) dal punto di vista proteomico, in particolare della caratterizzazione biochimica dei prioni e dei marcatori molecolari associati; successivamente ho iniziato anche ad interessarmi di proteomica liquorale e tissutale in altre malattie neurodegenerative, e della ricerca e caratterizzazione di nuovi marcatori molecolari di malattia. Nel laboratorio di Neuropatologia svolgo anche attivit\u00e0 di diagnostica molecolare delle malattie neurodegenerative.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-80\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG-291x300.png\" alt=\"LegnameG\" width=\"164\" height=\"169\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG-291x300.png 291w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LegnameG.png 297w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a><\/strong><strong>Giuseppe Legname.<\/strong><\/em>\u00a0Ha ottenuto il titolo di Doctor of Philosophy (equivalente a dottore di ricerca in Italia) presso l&#8217;Universita&#8217; di Warwick in Inghilterra. Dopo un lunga parentesi nell&#8217;industria farmaceutica, e&#8217; approdato nel 1996 al National Institute for Medical Research, Medical Research Council di Londra. Nel 1999 e&#8217; divenuto Assistant Adjunct Professor, e successivamente Associate Adjunct Professor presso l&#8217;Institute for Neurodegenerative Diseases, University of California at San Francisco, USA sotto la direzione del premio Nobel Stanley B. Prusiner. Da allora e&#8217; stato coinvolto in ricerche sullo studio dei prioni e delle malattie prioniche.<br \/>\nNel 2006, Giuseppe Legname ha vinto un concorso per il ruolo di professore associato presso la SISSA di Trieste, dove attualmente riveste la carica di coordinatore del dottorato in Genomica Funzionale e Strutturale. Il suo gruppo si occupa di ricerche sui prioni di mammifero<\/p>\n<p style=\"text-align: justify\">.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-81\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC-240x300.png\" alt=\"LigiosC\" width=\"164\" height=\"205\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC-240x300.png 240w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/LigiosC.png 272w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Ciriaco Ligios.\u00a0<\/strong><\/em>Nato il 10\/07\/1959. Laurea in Medicina Veterinaria conseguita il 10-11-1984, presso Facolt\u00e0 di Medicina Veterinaria dell\u2019Universit\u00e0 di Sassari. Dipendente dell\u2019Istituto Zooprofilattico Sperimentale della Sardegna, dal 01-08- 1990 come Veterinario I\u00b0 livello Dirigenziale, attualmente responsabile del laboratorio di Istopatologia Generale e Patologia e Diagnostica delle Encefalopatie Spongiformi Trasmissibili (TSE).<br \/>\nStage professionali relativi alla tematica della Summer School presso l\u2019Universita di Berna (CT) ed il centro di referenza Europeo delle TSE &#8211; Neuropathology Section of the Veterinary Laboratory Agency, Weybridge (UK) &#8211; nel 1999 e nel 2001. L\u2019attivit\u00e0 scientifica relativa alla tematica delle\u00a0 ricerca sulle TSE \u00e8 stata esposta in convegni nazionali ed internazionali ed in numerosi articoli pubblicati in riviste scientifiche nazionali ed internazionali e pu\u00f2 essere cos\u00ec riassunta: (1995-1998) Ricerche relative alla diagnostica, clinica e patologia della scrapie ovina.\u00a0 (1999-2003)\u00a0 Ricerche sul coinvolgimento del sistema linfatico nella patogenesi della scrapie, sulla differenziazione dei fenotipi di scrapie mediante il profilo istolesivo, sul ruolo dei vari polimorfismi del gene della PrP nei meccanismi di resistenza\/suscettibilit\u00e0 e sulla epidemiologia della scrapie in Sardegna. (2003-2010) Ricerche sulla relazione tra quadri infiammatori e distribuzione della PrP patologica nei vari organi extranervosi. In particolare in queste ricerche si \u00e8 studiato la co-infezione scrapie-virus Maedi-Visna ed infettivit\u00e0 prionica nel latte. Ricerca sulla associazione tra determinati dimorfismi del gene della proteina prionica e presenza\/assenza della proteina prionica patologica nella placenta. (2010-2014) Studio sulle mutazioni genetiche associate alla resistenza alla scrapie nelle capre. Studio del ruolo delle tonsille nella patogenesi della scrapie.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/Mandas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-96\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/Mandas.jpg\" alt=\"Mandas\" width=\"164\" height=\"213\" \/><\/a>Antonella Mandas.\u00a0<\/strong><\/em>Laureata in Medicina e Chirurgia, dal 2006 \u00e8 professore associato di medicina interna presso il Dipartimento di Scienze Mediche, Universit\u00e0 di Cagliari. Ha preso parte a studi clinici ed epidemiologici sulle infezioni da virus epatici e da HIV. In particolare, ha preso parte a importanti sperimentazioni cliniche sull\u2019 interferone in pazienti con epatite virale cronica. Ha condotto studi sullo stress ossidativo in geriatrica e nei soggetti con infezione da HIV. Negli anziani, \u00e8 stato messo in evidenza il legame tra stress ossidativo, comorbilit\u00e0, e stato nutrizionale. In soggetti con infezione da HIV \u00e8 stato evidenziato che la terapia antiretrovirale pu\u00f2 aumentare lo stress ossidativo. In cellule di linfomonociti da sangue periferico di pazienti con malattia di Alzheimer, gli studi delle alterazioni del colesterolo hanno suggerito che livelli di esteri del colesterolo possano essere utilizzati come biomarcatori precoci della malattia di Alzheimer. Negli anziani, studia la correlazione tra l&#8217;assunzione di farmaci ipolipemizzanti (statine) e deficit cognitivo. Dal 2007 \u00e8 Direttore della Scuola di Specializzazione Geriatria e conduce studi sulla valutazione geriatrica globale, come indicatore precoce della condizione della fragilit\u00e0 nell&#8217;anziano.<\/p>\n<p style=\"text-align: justify\"><em><strong><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/MeloniD-285x300.jpg\" alt=\"MeloniD\" width=\"164\" height=\"173\" \/>Daniela Meloni.\u00a0<\/strong><\/em>Gestisce del Laboratorio Diagnosi TSE del Centro di Referenza Nazionale per le Encefalopatie Animali presso l\u2019Istituto Zooprofilattico Sperimentale del Piemonte, Liguria e Valle d\u2019Aosta. Coordina le attivit\u00e0 relative alla sorveglianza attiva nazionale della BSE e della scrapie. In particolare si occupa di assicurare, standardizzare e monitorare la qualit\u00e0 diagnostica della rete dei laboratori test rapidi nazionali, offrire supporto tecnico ai laboratori, eseguire le attivit\u00e0 di Audit, collaudare nuovi lotti produttivi i test rapidi previa commercializzazione italiana ed europea, di pianificare la formazione nazionale ed internazionale nel settore di competenza. Si occupa di validazione di metodiche diagnostiche rapide e di ricerca e relativa divulgazione scientifica. E\u2019 autrice e coautrice di lavori scientifici pubblicati su riviste e presentati a congressi.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PaniA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-82\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PaniA.jpg\" alt=\"PaniA\" width=\"164\" height=\"156\" \/><\/a>Alessandra Pani.\u00a0<\/strong><\/em>Virologa, \u00e8 professore associato di microbiologia e virologia presso il Dipartimento di Scienze Biomediche dell\u2019Universit\u00e0 di Cagliari dal 2005. Da sempre si occupa di Drug Discovery di antivirali, in particolare di identificazione e caratterizzazione preclinica di nuovi inibitori selettivi di HIV, e di antitumorali, soprattutto associazioni di farmaci ad attivit\u00e0 sinergica, in vitro e in vivo. Come borsista CNR presso il Department of Virology del London Hospital Medical College di Londra, si \u00e8 anche occupata dei meccanismi della resistenza naturale alla infezione con herpes virus in topi inbred, e come post-doc nel Department of Molecular and Cellular Biology, University of Connecticut, ha studiato i meccanismi di shut-off della sintesi proteica in cellule infettate con picornavirus. In anni pi\u00f9 recenti, dopo un breve periodo presso il Department of Persistent Viral Diseases, RML, NIAID\/NIH, con alcuni post-doc e dottorandi del suo gruppo si interessa anche di alcuni aspetti relativi alle malattie da prioni e prion-like, in particolare il ruolo di colesterolo e lipidi nella generazione di aggregati amiloidi. E\u2019 Coordinatore del dottorato di ricerca in R&amp;D di Farmaci Anti-Infettivi e Vicecoordinatore del dottorato in Medicina Molecolare e Traslazionale.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PocchiariM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-83\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/PocchiariM.jpg\" alt=\"PocchiariM\" width=\"164\" height=\"203\" \/><\/a>Maurizio Pocchiari.\u00a0<\/strong><\/em>Neurologo, dirige il Dipartimento di Biologia Cellulare e Neuroscienze dell\u2019Istituto Superiore di Sanit\u00e0, Roma, dal 2011. Dal 1993 \u00e8 responsabile della sorveglianza nazionale della malattia di Creutzfeldt-Jakob e membro dello \u201cEUROCJD (Public Health Surveillance) Steering Group\u201d, European Centre for Disease Prevention and Control (ECDC). Dal 1978 si \u00e8 occupato di vari aspetti concernenti le malattie da prioni.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/07\/MariaPuopolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-208\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/07\/MariaPuopolo-150x150.jpg\" alt=\"MariaPuopolo\" width=\"164\" height=\"164\" \/><\/a>Maria Puopolo.\u00a0<\/strong><\/em>Statistico, ricercatore presso il Dipartimento di Biologia Cellulare e Neuroscienze dell&#8217;Istituto Superiore di Sanit\u00e0, Roma. Dal 2001 lavora nel campo delle malattie da prioni analizzando i dati della sorveglianza nazionale della malattia di Creutzfeldt-Jakob e della sorveglianza europea (EUROCJD). Nel 2014 \u00e8 consulente per European Centre for Disease Prevention and Control (ECDC) per l&#8217;analisi del TESSy vCJD database. Esperta in metodologie statistiche per analisi di: i) determinanti di progressione\/severit\u00e0 di malattia; ii) fattori di rischio e\/o protettivi; iii) sviluppo e validazione di biomarker; iv) valutazioni di efficacia di trattamenti sperimentali.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-84\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV-248x300.jpg\" alt=\"VetrugnoV\" width=\"164\" height=\"198\" srcset=\"https:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV-248x300.jpg 248w, https:\/\/sites.unica.it\/prion\/files\/2015\/06\/VetrugnoV.jpg 308w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/a>Vito Vetrugno.\u00a0<\/strong><\/em>Laurea in Scienze Biologiche nel 1992 presso l\u2019Universit\u00e0 degli Studi di Lecce (summa cum laude). Specializzazione in \u201cMicrobiologia e Virologia Medica\u201d (70\/70 cum laude), Universit\u00e0 \u201cLa Sapienza\u201d, Roma. Dal 1992 a oggi, ricercatore presso Istituto Superiore di Sanit\u00e0 (ISS), in Roma. Dal 2009, docente a contratto dell\u2019insegnamento \u201cMetodologia della Ricerca\u201d nel Master Universitario di Primo Livello \u201cManagement della Professione Sanitaria\u201d, presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Roma. Dal 2010, Coordinatore del Gruppo di Lavoro sulle Encefalopatie Spongiformi Trasmissibili (GESTISS) presso l\u2019ISS. La sua principale area di interesse \u00e8 lo studio dell\u2019impatto delle Encefalopatie Spongiformi Trasmissibili (EST o malattie da prioni) sulla salute pubblica. E\u2019 pertanto coinvolto in una vasta attivit\u00e0 che riguarda la ricerca pre-normativa, consultazioni regolatorie (es. autorizzazioni immissione in commercio di specialit\u00e0 medicinali e rilascio di certificazioni CE per dispositivi medici impiantabili) e consulenza, con pi\u00f9 di quattrocento pareri scientifici e valutazioni del rischio EST elaborate. Come ricercatore, si occupa della biologia cellulare della proteina prionica e della sua conversione nell\u2019isoforma patologica e dello sviluppo di nuovi approcci terapeutici in modelli preclinici.<\/p>\n<p style=\"text-align: justify\"><em><strong><a href=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/ZanussoG.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-85\" src=\"http:\/\/sites.unica.it\/prion\/files\/2015\/06\/ZanussoG.jpg\" alt=\"ZanussoG\" width=\"164\" height=\"212\" \/><\/a>Gianluigi Zanusso.\u00a0<\/strong><\/em>Professore associato in neurologia presso il Dipartimento di Scienze Neurologiche del Movimento, Universit\u00e0 di Verona dal 2014. Ha iniziato ad occuparsi di malattie da prioni nel 1995, studiando prima i meccanismi molecolari di aggregazione dei prioni in modelli cellulari di forme genetiche, per dedicarsi poi agli aspetti clinici delle malattie umane dedicando particolare interesse al coinvolgimento del sistema olfattorio e alla diagnostica in vita della Malattia di Creutzfeldt-Jakob (MCJ). Dal 2001 al 2007 \u00e8 stato membro della Commissione Ministeriale denominata Task Force Nazionale delle Encefalopatie Spongiformi Trasmissibili. Recentemente in collaborazione con il gruppo del Dr. Caughey del NIAID nel Montana, ha messo a punto un test in vita per la (MCJ) mediante brushing nasale.<\/p>\n<p><em style=\"text-align: justify\">\u00a0<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>en Lorenzo Capucci.\u00a0graduated in Biological Science at the State University of Milano in 1981. He works at the Istituto Zooprofilattico Sperimentale della Lombardia e dell\u2019 Emilia Romagna (IZSLER) since 1983. At present he is responsible of the Proteomic Structures\/Genomics-Department at IZSLER. He is working on the diagnosis and study of the main viral diseases of &hellip; <a href=\"https:\/\/sites.unica.it\/prion\/edition-2015\/lecturers-2015\/\" class=\"more-link\">Continua la lettura di <span class=\"screen-reader-text\">Lecturers 2015<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":165,"featured_media":0,"parent":245,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-263","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/pages\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":1,"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"predecessor-version":[{"id":264,"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/pages\/263\/revisions\/264"}],"up":[{"embeddable":true,"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/pages\/245"}],"wp:attachment":[{"href":"https:\/\/sites.unica.it\/prion\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}